{"id":183,"date":"2016-09-20T23:47:39","date_gmt":"2016-09-20T21:47:39","guid":{"rendered":"https:\/\/quantenfrosch.at\/blog\/?p=183"},"modified":"2018-08-23T23:51:56","modified_gmt":"2018-08-23T21:51:56","slug":"onpage-optimierung-wordpress-seo-tipps","status":"publish","type":"post","link":"https:\/\/quantenfrosch.at\/blog\/onpage-optimierung-wordpress-seo-tipps\/","title":{"rendered":"OnPage Optimierung &#8211; die besten Wordpress SEO Tipps"},"content":{"rendered":"<p>Es hat einige Zeit gedauert, doch die Webseite ist fertig. Sie wurde mit WordPress erstellt und enth\u00e4lt lesenswerte Artikel. Nun m\u00fcssen Sie sich um die Suchmaschinenoptimierung k\u00fcmmern: Denn ein hohes Google Ranking kommt nicht von selbst, sondern erfordert ein gutes Konzept. Hier erhalten Sie hilfreiche Infos zur <strong>OnPage Optimierung<\/strong> speziell f\u00fcr <strong>WordPress<\/strong>.<\/p>\n<h2>OnPage Optimierung kann auch einfach sein<\/h2>\n<p>Daf\u00fcr braucht es ein kostenloses <strong>Plugin <\/strong>wie <a href=\"https:\/\/de.wordpress.org\/plugins\/wordpress-seo\/\" target=\"_blank\" rel=\"noopener noreferrer\">YOAST Plugin<\/a>. Alternativ kommen <a href=\"https:\/\/de.wordpress.org\/plugins\/all-in-one-seo-pack\/\" target=\"_blank\" rel=\"noopener noreferrer\">All in One SEO Pack<\/a> oder <a href=\"https:\/\/wpseo.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">wpSEO <\/a>infrage. Sie sind simpel gestaltet und auch f\u00fcr Anf\u00e4nger geeignet. So zeigt ein Ampelsystem bei Yoast an, wie gut ein Beitrag optimiert ist. Anstatt dieser &#8222;gro\u00dfen L\u00f6sung&#8220; k\u00f6nnen Sie ein kleines Plugin f\u00fcr eine bestimmte Funktion installieren. Die Tools sollten in den letzten Monaten wenigstens ein Update erhalten haben, sonst k\u00f6nnten sie veraltet sein.<\/p>\n<h3>Ist das Seitenthema technisch ausgereift?<\/h3>\n<p>Bevor Sie sich in Details verrennen, sollten Sie diese Grundfrage kl\u00e4ren. <strong>Responsive Webdesign<\/strong> ist Pflicht, um ein hohes Google Ranking zu erhalten. <strong>Schnelle Ladezeiten<\/strong> sind ein weiterer Pluspunkt, wobei es die Dateien zu optimieren gilt. Mit dem Plugin <a href=\"https:\/\/de.wordpress.org\/plugins\/imagify\/\" target=\"_blank\" rel=\"noopener noreferrer\">Imagify <\/a>k\u00f6nnen Sie die Fotos direkt beim Upload komprimieren.<\/p>\n<h3>Sitemaps: Wegweiser f\u00fcr Roboter<\/h3>\n<p>Eine Suchmaschine muss sich den Weg durch Ihre Seite bahnen. Da sie keine Augen hat, ist sie auf Hilfsmittel angewiesen. Vor allem auf gro\u00dfen Seiten kann sich der Bot leicht verirren. Eine <strong>XML-Sitemap<\/strong> ist ein simpler Ausweg: Sie ist in quasi jedem SEO Tool enthalten oder kann separat als Plugin installiert werden. Hier hat sich das <a href=\"https:\/\/de.wordpress.org\/plugins\/google-sitemap-generator\/\" target=\"_blank\" rel=\"noopener noreferrer\">Google XML-Sitemaps<\/a> Plugin als kompetenter Seitenf\u00fchrer bew\u00e4hrt.<\/p>\n<h3>Starke, sprechende Linktitel setzen<\/h3>\n<p>Bei der OnPage Optimierung kommt es darauf an, eine Seite m\u00f6glichst benutzerfreundlich zu gestalten. Schlie\u00dflich soll der Nutzer eine Weiterleitung als hilfreich und nicht etwa als Spam einordnen. Manche Webmaster sind darauf angewiesen, dass der Besucher auf den Link klickt, damit sie eine Provision erhalten. Selbst kleine Details k\u00f6nnen f\u00fcr h\u00f6here Ertr\u00e4ge sorgen.<\/p>\n<p>Sobald Sie ein Wort markieren und auf das Link-Symbol klicken, poppt ein weiteres Fenster auf. Hier k\u00f6nnen Sie sich f\u00fcr einen <strong>aussagekr\u00e4ftigen Titel<\/strong> f\u00fcr den Link entscheiden. So erh\u00f6hen Sie die Usability einer Webseite!<\/p>\n<p>Im Bereich der OnPage Optimierung k\u00f6nnen Sie immer dasselbe Keyword verlinken, das macht Google nichts aus. Anders verh\u00e4lt es sich bei Links auf externen Webseiten: Wenn Sie st\u00e4ndig den Begriff &#8222;g\u00fcnstiges Hundefutter&#8220; verwenden, k\u00f6nnten Sie einen Penalty erhalten.<\/p>\n<p><strong>Permalinks <\/strong>sind ein weiterer Aspekt der Suchmaschinenoptimierung. Eine willk\u00fcrliche Zahlenreihe in der URL macht keinen guten Eindruck beim Besucher. Lassen Sie die Links sprechen, was Ihnen Nutzer und Roboter danken werden. W\u00e4hlen Sie den Reiter &#8222;Einstellungen&#8220; und im Anschluss den Punkt &#8222;Permalinks&#8220; aus.<\/p>\n<h3>Struktur der Texte<\/h3>\n<p>Ein Artikel sollte mit <strong>einer<\/strong> Haupt\u00fcberschrift (H1) beginnen. In der Regel ist das in WordPress voreingestellt und Sie m\u00fcssen keine \u00c4nderungen vornehmen. Anders verh\u00e4lt es sich im Artikel: Hier sollten Sie zwei bis vier Sub-Headlines mit H2 definieren, abh\u00e4ngig von der L\u00e4nge des Textes. Verzichten Sie auf lustige Wortspiele, denn klare Titel lassen sich besser finden. F\u00fcr die <a href=\"https:\/\/quantenfrosch.at\/blog\/seo-aktuell\/\">Suchmaschinenoptimierung <\/a>sollten Sie das Keyword in der H1 und einer H2 \u00dcberschrift unterbringen.<\/p>\n<h3>OnPage SEO &#8211; Grunddaten einer Webseite<\/h3>\n<p>Jeder Mensch hat einen Vor- und Nachnamen. Bei einer Homepage sind es die <strong>Meta-Informationen<\/strong>, die ihr einen individuellen Touch verleihen. \u00dcberlegen Sie sich einen passenden Titel und eine eindeutige Beschreibung. Sucht jemand nach Ihrer Seite, tauchen diese Angaben in den Suchergebnissen auf. Dar\u00fcber hinaus sollten Sie f\u00fcr Artikel und Seiten eigene Meta-Angaben machen. Das hat den Vorteil, dass zu jedem Keyword ein eigener Text bei Google erscheint.<\/p>\n<p>Generell sollten Sie die Artikel und Seiten individuell optimieren: Bei den Schl\u00fcsselw\u00f6rter d\u00fcrfen Sie Tools wie dem Yoast Plugin nicht blind vertrauen. Google achtet immer mehr auf gute Inhalte und da geh\u00f6ren Variationen des Keywords dazu. Leider versagen manche Tools bereits beim Erkennen der Pluralform. WordPress ist eine n\u00fctzliche Web-Software, aber sie ist nicht perfekt, was besonders f\u00fcr die Plugins gilt.<\/p>\n<p>Zudem sollten Sie einzelne <strong>Werbe-Links auf NoFollow<\/strong> setzen. Einige Webmaster stellen die Konkurrenz gezielt auf NoIndex, doch diese Ansicht ist veraltet. Eher im Gegenteil: Die Besucher bleiben l\u00e4nger auf Ihrer Seite, was f\u00fcr Sie eine l\u00e4ngere Verweildauer bedeutet &#8211; und das ist ein gro\u00dfartiges Rankingkriterium!<\/p>\n<p>Info: In manchen Blogs wird das Authorship empfohlen, aber diese Funktion wurde von Google Ende 2014 aufgegeben.<\/p>\n<h5>SEO: Bilder beschreiben<\/h5>\n<p>Google kann keine Bilder auf Ihrer WordPress Seite &#8222;ansehen&#8220;. Die Suchmaschine erkennt nur den Text, der in der Beschreibung geschrieben steht. Daher sollten Sie sich Gedanken \u00fcber die richtige Beschreibung machen. Die Bildersuche von Google ist eine wertvolle Trafficquelle, die h\u00e4ufig untersch\u00e4tzt wird. Der Dateiname des Fotos sollte das Keyword oder eine Variation enthalten. Rufen Sie daf\u00fcr den Reiter &#8222;Medien&#8220; auf und w\u00e4hlen Sie das gew\u00fcnschte Bild aus. Hier k\u00f6nnen Sie \u00c4nderungen f\u00fcr die Suchmaschinenoptimierung vornehmen.<\/p>\n<p>Fazit: Diese Tipps lassen sich in WordPress relativ schnell in die Praxis umsetzen. Mit einem Tool wie dem Yoast Plugin behalten Sie die meisten SEO Ma\u00dfnahmen im Blick. Bei den Keyw\u00f6rtern sollten Sie jedoch genau pr\u00fcfen, ob auch Pluralformen oder Variationen analysiert werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es hat einige Zeit gedauert, doch die Webseite ist fertig. Sie wurde mit WordPress erstellt und enth\u00e4lt lesenswerte Artikel. Nun m\u00fcssen Sie sich um die Suchmaschinenoptimierung k\u00fcmmern: Denn ein hohes<\/p>\n","protected":false},"author":6,"featured_media":180,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","rank_math_title":"OnPage Optimierung - die besten Wordpress SEO Tipps","rank_math_description":"Wordpress OnPage Optimierung, SEO Tipps f\u00fcr n\u00fctzliche Plugins und Technik sowie der Strukturierung von Texten und Verlinkungen.","rank_math_focus_keyword":"onpage"},"categories":[12],"tags":[17,14],"class_list":["post-183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wordpress","tag-plugins","tag-ranking"],"_links":{"self":[{"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/posts\/183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/comments?post=183"}],"version-history":[{"count":0,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/posts\/183\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/media\/180"}],"wp:attachment":[{"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/media?parent=183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/categories?post=183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/tags?post=183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}