{"id":218,"date":"2017-06-04T22:42:58","date_gmt":"2017-06-04T20:42:58","guid":{"rendered":"https:\/\/quantenfrosch.at\/blog\/?p=218"},"modified":"2018-08-24T22:45:37","modified_gmt":"2018-08-24T20:45:37","slug":"tipps-fuer-ihre-landing-pages","status":"publish","type":"post","link":"https:\/\/quantenfrosch.at\/blog\/tipps-fuer-ihre-landing-pages\/","title":{"rendered":"Die besten Tipps f\u00fcr Ihre Landing Pages"},"content":{"rendered":"<p>Falls Sie sich bereits intensiver mit der Optimierung einer Web-Pr\u00e4senz besch\u00e4ftigt haben, ist Ihnen wahrscheinlich schon einmal der Begriff <strong>Landing Page<\/strong> begegnet. Landing Page bedeutet frei \u00fcbersetzt so viel wie &#8222;Landeseite&#8220;. Im \u00fcbertragenen Sinn haben Landing Pages auch genau diesen Zweck. Es handelt sich um speziell erstellte Webseiten, die Nutzern als &#8222;Landebahn&#8220; dienen.<\/p>\n<h2>Der Unterschied zwischen normalen Webseiten und Landing Pages<\/h2>\n<p>Ein Internetnutzer startet eine Suchanfrage oder er klickt auf einen Link auf einer Webseite, der zu Ihrem Webauftritt f\u00fchrt. Im optimalen Fall landet er dann nicht auf einer beliebigen Seite Ihrer Webpr\u00e4senz, sondern auf einer Ihrer Landing Pages. Diese Seiten m\u00fcssen demnach auf die entsprechenden Werbetr\u00e4ger und Zielgruppen ausgerichtet sein. Dar\u00fcber hinaus sind sie einfach gestaltet und pr\u00e4sentieren genau den vom Nutzer gesuchten Begriff.<\/p>\n<p>W\u00fcrde der Internetnutzer nach seinem Klick direkt auf Ihrer Webpr\u00e4senz landen, so w\u00fcrden ihn dort die zahlreichen anderen Informationen, wie Unternehmensbeschreibung, Firmengeschichte, Referenzen, Angebote, Men\u00fcs und Buttons nur ablenken oder schlimmstenfalls verwirren, dass er Ihre Seite nach kurzem Dr\u00fcberschauen wieder verl\u00e4sst. Ein potenzieller Kunde w\u00e4re verloren.<\/p>\n<p>Wird der User dagegen auf eine Landing Page weitergeleitet, findet er sich auf einer \u00fcberschaubaren Seite wieder. Hier geht es ausschlie\u00dflich um das gesuchte Produkt oder die gew\u00fcnschte Dienstleistung mit den wichtigsten Informationen.<\/p>\n<h3>Die besten Tipps f\u00fcr die Umsetzung erfolgreicher Landing Pages<\/h3>\n<ol>\n<li><strong>Weniger ist mehr:<\/strong> Sorgen Sie f\u00fcr wenig Ablenkung vom wesentlichen Inhalt. Das bedeutet im Idealfall keine weiterf\u00fchrenden Links, keine Men\u00fcleiste und nur kurze Textabschnitte oder Listen, sowie wenige Fotos, die genau zum Thema bzw. Angebot passen.<\/li>\n<li><strong>Klare Handlungsaufforderung:<\/strong> Fordern Sie den Nutzer auf, etwas Konkretes zu tun, das in Ihrem Interesse ist. Die <a href=\"https:\/\/chimpify.de\/marketing\/call-to-action\/\" target=\"_blank\" rel=\"noopener noreferrer\">Handlungssaufforderung <\/a>(&#8222;Call to Action&#8220;) ist die Ziellinie der Landing Page. Das ist beispielsweise einen Button anzuklicken (z.B. der Button &#8222;In den Warenkorb legen&#8220; in einem <a href=\"https:\/\/quantenfrosch.at\/blog\/produkte-in-woocommerce-anlegen\/\">Onlineshop<\/a>), einen Newsletter zu abonnieren, ein Kontaktformular ausf\u00fcllen oder eine Email zu senden.<br \/>\nSetzen Sie nach M\u00f6glichkeit nur <strong>eine <\/strong>Handlungsaufforderung auf Ihrer Landing Page. Denn je mehr Auswahl zum Handeln vorhanden ist, umso gr\u00f6\u00dfer wird die Ablenkung f\u00fcr den Nutzer.<\/li>\n<li><strong>Pr\u00e4gnante \u00dcberschrift und verst\u00e4ndlicher Textaufbau:<\/strong> Im Idealfall wird die Aufmerksamkeit der Nutzer auf Ihrer Landing Page so gefesselt, dass sie am Ende Schritt f\u00fcr Schritt bis zur Ausf\u00fchrung der Handlungsaufforderung (Button dr\u00fccken, E-Mail-Adresse eingeben, Newsletter bestellen) gef\u00fchrt werden.<\/li>\n<\/ol>\n<h3>Welche Ziele lassen sich mit Landing Pages umsetzen?<\/h3>\n<p>Eine Landing Page ist ein effizientes und dar\u00fcber hinaus relativ kostenschonendes Marketing-Werkzeug. Das prim\u00e4re Ziel besteht darin, interessierte Nutzer als Kunden oder Auftraggeber zu gewinnen. Um das zu erreichen, bedienen sich Marketingstrategen diverser Tools, die ebenfalls integriert werden k\u00f6nnen.<\/p>\n<ul class=\"square\">\n<li>Umfragen zum Sammeln von E-Mail-Adressen potenzieller Kunden<\/li>\n<li>Verkauf von Dienstleistungen oder Produkten<\/li>\n<li>Vermarktung von Rabatt- oder Sonderaktionen<\/li>\n<li>Gewinnspiele<\/li>\n<li>Formulare zum Bestellen von Newslettern oder zur Kontaktaufnahme<\/li>\n<\/ul>\n<p><strong>Eine Landing Page sollte einem Endzweck dienen und die Nutzer gezielt bis zur Ausf\u00fchrung der Handlungsaufforderung leiten.<\/strong><\/p>\n<p>Jedes Unternehmen, das sein Angebot im Internet vermarktet, kann mit Landing Pages die Interaktionsrate der Nutzer erh\u00f6hen. Und da der Aufbau dieser speziellen Seiten vergleichsweise einfach ist, l\u00e4sst sich auch mit kleineren Budgets, viel erreichen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Falls Sie sich bereits intensiver mit der Optimierung einer Web-Pr\u00e4senz besch\u00e4ftigt haben, ist Ihnen wahrscheinlich schon einmal der Begriff Landing Page begegnet. Landing Page bedeutet frei \u00fcbersetzt so viel wie<\/p>\n","protected":false},"author":6,"featured_media":216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","rank_math_title":"Die wichtigsten Tipps f\u00fcr erfolgreiche Landing Pages","rank_math_description":"Die besten Tipps f\u00fcr die Erstellung von Landing Pages. Erfahren Sie mehr \u00fcber die wichtigsten Merkmale erfolgreicher Landig Pages.","rank_math_focus_keyword":"landing pages"},"categories":[6],"tags":[35,18],"class_list":["post-218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-online-marketing","tag-design","tag-digitales-marketing"],"_links":{"self":[{"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/posts\/218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/comments?post=218"}],"version-history":[{"count":0,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/posts\/218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/media\/216"}],"wp:attachment":[{"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/media?parent=218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/categories?post=218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quantenfrosch.at\/blog\/wp-json\/wp\/v2\/tags?post=218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}